{"id":38939,"date":"2025-07-02T11:27:51","date_gmt":"2025-07-02T09:27:51","guid":{"rendered":"https:\/\/www.machiweb.com\/?post_type=annonce&#038;p=38939"},"modified":"2025-07-02T11:43:46","modified_gmt":"2025-07-02T09:43:46","slug":"benne-huret-3-essieux","status":"publish","type":"annonce","link":"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/","title":{"rendered":"Benne Huret 3 essieux"},"content":{"rendered":"<p>Benne 3 essieux Huret disponible<\/p>\n<p>Nous sommes joignable 7j\/7<\/p>\n<p>F\u00fcr Deutch bitte anrufen sie Bernardo, wir helfen sie<br \/>\nFor english plaese call Bernardo<br \/>\nVoor nederlands gelieve Bernardo te bellen, wij helpen u graag verder.<\/p>\n<p>Service financement<br \/>\nService de transport<br \/>\nReprise possible<\/p>\n<p>Suivi clients: cartes grises, livraison, transport etc.<br \/>\nEquipement &amp; option a la carte sur demande.<\/p>\n<p>Benne \u00e9quip\u00e9 de:<\/p>\n<p>23.5T Tr\u00e8s bon \u00e9tat<\/p>\n<p>\u27053 essieux<br \/>\n\u2705Timon suspendu hydraulique<br \/>\n\u2705Attelage boulonn\u00e9 K80<br \/>\n\u2705Essieux a suspension hydraulique<br \/>\n\u2705Essieux directeurs forc\u00e9s<br \/>\n\u2705Freinage pneumatique<br \/>\n\u2705Porte hydraulique &amp; 2 portes c\u00e9r\u00e9ales<br \/>\n\u2705R\u00e9hausse + recouvrement hydraulique bache<br \/>\n\u2705Eclairage full Led<\/p>\n","protected":false},"author":13,"featured_media":38984,"menu_order":0,"template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"materiel":[1446],"marque":[1723],"equipement":[1697,382,357,351],"boite-de-vitesse":[],"version":[],"attelage":[],"nombre-d-essieux":[1664],"class_list":["post-38939","annonce","type-annonce","status-publish","has-post-thumbnail","hentry","materiel-benne-cerealiere-nl","marque-huret","equipement-bequille-hydraulique","equipement-essieu-suiveur","equipement-freins-pneumatiques","equipement-porte-hydraulique","nombre-d-essieux-1664"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Benne Huret 3 essieux \u00e0 vendre sur Machiweb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Benne Huret 3 essieux \u00e0 vendre sur Machiweb\" \/>\n<meta property=\"og:description\" content=\"Benne 3 essieux Huret disponible Nous sommes joignable 7j\/7 F\u00fcr Deutch bitte anrufen sie Bernardo, wir helfen sie For english plaese call Bernardo Voor nederlands gelieve Bernardo te bellen, wij helpen u graag verder. Service financement Service de transport Reprise possible Suivi clients: cartes grises, livraison, transport etc. Equipement &amp; option a la carte sur [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/\" \/>\n<meta property=\"og:site_name\" content=\"MachiWeb\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T09:43:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439\" \/>\n\t<meta property=\"og:image:width\" content=\"709\" \/>\n\t<meta property=\"og:image:height\" content=\"945\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/\",\"url\":\"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/\",\"name\":\"Benne Huret 3 essieux \u00e0 vendre sur Machiweb\",\"isPartOf\":{\"@id\":\"https:\/\/www.machiweb.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439\",\"datePublished\":\"2025-07-02T09:27:51+00:00\",\"dateModified\":\"2025-07-02T09:43:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/#primaryimage\",\"url\":\"https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439\",\"contentUrl\":\"https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439\",\"width\":709,\"height\":945},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.machiweb.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Annonces\",\"item\":\"https:\/\/www.machiweb.com\/de\/annonce\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Landwirtschaftlich\",\"item\":\"https:\/\/www.machiweb.com\/de\/materiel\/agricole-de\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Anh\u00e4nger\",\"item\":\"https:\/\/www.machiweb.com\/de\/materiel\/agricole-de\/remorque-de\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"M\u00fcslikipper\",\"item\":\"https:\/\/www.machiweb.com\/de\/materiel\/agricole-de\/remorque-de\/benne-cerealiere-de\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Benne Huret 3 essieux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.machiweb.com\/de\/#website\",\"url\":\"https:\/\/www.machiweb.com\/de\/\",\"name\":\"MachiWeb\",\"description\":\"le site de petites annonces de mat\u00e9riel agricole\",\"publisher\":{\"@id\":\"https:\/\/www.machiweb.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.machiweb.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.machiweb.com\/de\/#organization\",\"name\":\"MachiWeb\",\"url\":\"https:\/\/www.machiweb.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.machiweb.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.machiweb.com\/wp-content\/uploads\/2022\/07\/cropped-logo-machiweb-website-1.png?v=1743253573\",\"contentUrl\":\"https:\/\/www.machiweb.com\/wp-content\/uploads\/2022\/07\/cropped-logo-machiweb-website-1.png?v=1743253573\",\"width\":1000,\"height\":185,\"caption\":\"MachiWeb\"},\"image\":{\"@id\":\"https:\/\/www.machiweb.com\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Benne Huret 3 essieux \u00e0 vendre sur Machiweb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/","og_locale":"de_DE","og_type":"article","og_title":"Benne Huret 3 essieux \u00e0 vendre sur Machiweb","og_description":"Benne 3 essieux Huret disponible Nous sommes joignable 7j\/7 F\u00fcr Deutch bitte anrufen sie Bernardo, wir helfen sie For english plaese call Bernardo Voor nederlands gelieve Bernardo te bellen, wij helpen u graag verder. Service financement Service de transport Reprise possible Suivi clients: cartes grises, livraison, transport etc. Equipement &amp; option a la carte sur [&hellip;]","og_url":"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/","og_site_name":"MachiWeb","article_modified_time":"2025-07-02T09:43:46+00:00","og_image":[{"width":709,"height":945,"url":"https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/","url":"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/","name":"Benne Huret 3 essieux \u00e0 vendre sur Machiweb","isPartOf":{"@id":"https:\/\/www.machiweb.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/#primaryimage"},"image":{"@id":"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439","datePublished":"2025-07-02T09:27:51+00:00","dateModified":"2025-07-02T09:43:46+00:00","breadcrumb":{"@id":"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/#primaryimage","url":"https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439","contentUrl":"https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439","width":709,"height":945},{"@type":"BreadcrumbList","@id":"https:\/\/www.machiweb.com\/de\/annonce\/benne-huret-3-essieux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.machiweb.com\/de\/"},{"@type":"ListItem","position":2,"name":"Annonces","item":"https:\/\/www.machiweb.com\/de\/annonce\/"},{"@type":"ListItem","position":3,"name":"Landwirtschaftlich","item":"https:\/\/www.machiweb.com\/de\/materiel\/agricole-de\/"},{"@type":"ListItem","position":4,"name":"Anh\u00e4nger","item":"https:\/\/www.machiweb.com\/de\/materiel\/agricole-de\/remorque-de\/"},{"@type":"ListItem","position":5,"name":"M\u00fcslikipper","item":"https:\/\/www.machiweb.com\/de\/materiel\/agricole-de\/remorque-de\/benne-cerealiere-de\/"},{"@type":"ListItem","position":6,"name":"Benne Huret 3 essieux"}]},{"@type":"WebSite","@id":"https:\/\/www.machiweb.com\/de\/#website","url":"https:\/\/www.machiweb.com\/de\/","name":"MachiWeb","description":"le site de petites annonces de mat\u00e9riel agricole","publisher":{"@id":"https:\/\/www.machiweb.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.machiweb.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.machiweb.com\/de\/#organization","name":"MachiWeb","url":"https:\/\/www.machiweb.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.machiweb.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.machiweb.com\/wp-content\/uploads\/2022\/07\/cropped-logo-machiweb-website-1.png?v=1743253573","contentUrl":"https:\/\/www.machiweb.com\/wp-content\/uploads\/2022\/07\/cropped-logo-machiweb-website-1.png?v=1743253573","width":1000,"height":185,"caption":"MachiWeb"},"image":{"@id":"https:\/\/www.machiweb.com\/de\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439",709,945,false],"thumbnail":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172-113x150.jpg?v=1751448439",113,150,true],"medium":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172-225x300.jpg?v=1751448439",225,300,true],"medium_large":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439",709,945,false],"large":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439",709,945,false],"1536x1536":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439",709,945,false],"2048x2048":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439",709,945,false],"gform-image-choice-sm":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439",225,300,false],"gform-image-choice-md":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439",300,400,false],"gform-image-choice-lg":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172.jpg?v=1751448439",450,600,false],"woocommerce_thumbnail":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172-300x300.jpg?v=1751448439",300,300,true],"woocommerce_single":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172-600x800.jpg?v=1751448439",600,800,true],"woocommerce_gallery_thumbnail":["https:\/\/www.machiweb.com\/wp-content\/uploads\/2025\/07\/IMG-20250701-WA0172-100x100.jpg?v=1751448439",100,100,true]},"uagb_author_info":{"display_name":"Lilux","author_link":"https:\/\/www.machiweb.com\/de\/author\/lilux\/"},"uagb_comment_info":0,"uagb_excerpt":"Benne 3 essieux Huret disponible Nous sommes joignable 7j\/7 F\u00fcr Deutch bitte anrufen sie Bernardo, wir helfen sie For english plaese call Bernardo Voor nederlands gelieve Bernardo te bellen, wij helpen u graag verder. Service financement Service de transport Reprise possible Suivi clients: cartes grises, livraison, transport etc. Equipement &amp; option a la carte sur&hellip;","_links":{"self":[{"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/annonce\/38939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/annonce"}],"about":[{"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/types\/annonce"}],"author":[{"embeddable":true,"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/users\/13"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/media\/38984"}],"wp:attachment":[{"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/media?parent=38939"}],"wp:term":[{"taxonomy":"materiel","embeddable":true,"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/materiel?post=38939"},{"taxonomy":"marque","embeddable":true,"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/marque?post=38939"},{"taxonomy":"equipement","embeddable":true,"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/equipement?post=38939"},{"taxonomy":"boite-de-vitesse","embeddable":true,"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/boite-de-vitesse?post=38939"},{"taxonomy":"version","embeddable":true,"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/version?post=38939"},{"taxonomy":"attelage","embeddable":true,"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/attelage?post=38939"},{"taxonomy":"nombre-d-essieux","embeddable":true,"href":"https:\/\/www.machiweb.com\/de\/wp-json\/wp\/v2\/nombre-d-essieux?post=38939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}